{"id":506,"date":"2016-01-02T00:28:52","date_gmt":"2016-01-02T00:28:52","guid":{"rendered":"http:\/\/avadellaira.com\/love-letters\/querido-kurt-cobain-3\/"},"modified":"2016-01-02T00:28:52","modified_gmt":"2016-01-02T00:28:52","slug":"querido-kurt-cobain-3","status":"publish","type":"post","link":"https:\/\/loveletters.avadellaira.com\/love-letters\/querido-kurt-cobain-3\/","title":{"rendered":"Querido Kurt Cobain"},"content":{"rendered":"<p>La verdad que me gusta mucho tu musica. Hace poco que te conosco (dos semanas) Si no fuera por el libro \u201cLove letters to the dead\u201d nunca hubiera buscado el album In Utero (que se convirtio en mi favorito) y hubiera escuchado tu musica. Para Navidad me regalaron 2 remeras de Nirvana que adoro (ahora llevo una). Amo una frase tulla que es \u201cSe rien de mi por que soy diferente, yo me rio de ellos por que son todos iguales\u201d hace varios meses, habia leido esa frase en una historia fanficion de un youtuber en Wattpad y la puse en mi habitacion. Yo creo que si vieras a tu hija, Frances (si no mal recuerdo su nombre era ese) estarias super orgulloso de ella. Sinceramente no tengo mucho mas que decir, el otro dia me di cuenta que cumples a\u00f1os el mismo dia que mi hermana\u2026 Sea donde sea que te encuentres, en otra vida, en un objeto, en una planta, en el cielobo donde sea, quiero que sepas que te quiero (aun que es 99% imposible que leas esto). Quien sabe? Por ahi aunque sea una chica yo soy vos, es decir vos reencatnaste en mi. Tienes un espacio en mi corazon Kurt.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La verdad que me gusta mucho tu musica. Hace poco que te conosco (dos semanas) Si no fuera por el libro \u201cLove letters to the dead\u201d nunca hubiera buscado el album In Utero (que se convirtio en mi favorito) y hubiera escuchado tu musica. Para Navidad me regalaron 2 remeras de Nirvana que adoro (ahora [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[2],"tags":[],"class_list":["post-506","post","type-post","status-publish","format-standard","hentry","category-love-letters"],"acf":[],"_links":{"self":[{"href":"https:\/\/loveletters.avadellaira.com\/love-letters\/wp-json\/wp\/v2\/posts\/506","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/loveletters.avadellaira.com\/love-letters\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/loveletters.avadellaira.com\/love-letters\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/loveletters.avadellaira.com\/love-letters\/wp-json\/wp\/v2\/comments?post=506"}],"version-history":[{"count":0,"href":"https:\/\/loveletters.avadellaira.com\/love-letters\/wp-json\/wp\/v2\/posts\/506\/revisions"}],"wp:attachment":[{"href":"https:\/\/loveletters.avadellaira.com\/love-letters\/wp-json\/wp\/v2\/media?parent=506"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/loveletters.avadellaira.com\/love-letters\/wp-json\/wp\/v2\/categories?post=506"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/loveletters.avadellaira.com\/love-letters\/wp-json\/wp\/v2\/tags?post=506"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}