{"id":517,"date":"2016-01-07T17:30:27","date_gmt":"2016-01-07T17:30:27","guid":{"rendered":"http:\/\/avadellaira.com\/love-letters\/querido-vovo-2\/"},"modified":"2016-01-07T17:30:27","modified_gmt":"2016-01-07T17:30:27","slug":"querido-vovo-2","status":"publish","type":"post","link":"https:\/\/loveletters.avadellaira.com\/love-letters\/querido-vovo-2\/","title":{"rendered":"Querido Vov\u00f4"},"content":{"rendered":"<p>Quando o senhor se foi, eu tinha 7 anos. N\u00f3s n\u00e3o est\u00e1vamos na mesma cidade. Eu lembro do telefone tocando, da minha madrinha atendendo, olhando-me e anunciando: &#8220;o vov\u00f4 morreu&#8221;. Eu n\u00e3o posso dizer o que senti naquela \u00e9poca porque eu n\u00e3o tenho certeza se podia compreender o que aquelas tr\u00eas palavras queriam dizer. Mas, sabe, depois de um tempo eu senti bastante. Tenho poucas lembran\u00e7as, mas a mais n\u00edtida foi de certa vez em que o senhor me deixou usar um martelo para fazer cacos. O senhor improvisou um martelo para poder fazer o mesmo, j\u00e1 que a \u00fanica ferramenta eficaz para o servi\u00e7o estava comigo e eu estava mais brincando do que qualquer outra coisa. O senhor me mimou dessa vez e eu quero ter mais lembran\u00e7as que essa, mas n\u00e3o tenho. A mam\u00e3e ficou bem triste com a sua partida, como era de se esperar. Ela viajou at\u00e9 onde o senhor estava, mas n\u00e3o o encontrou com vida. Temos fotos do seu vel\u00f3rio. Deu para notar que o senhor era bem querido porque as pessoas nas fotos parecem realmente afetadas com a sua partida. A minha av\u00f3 tamb\u00e9m sente muito a sua falta, mas ela poderia ser um pouco menos teimosa e nos ajudar a cuidar da sa\u00fade dela. Seus filhos continuam sendo pessoas honestas. E posso afirmar que uma de suas filhas \u00e9 a melhor m\u00e3e do mundo. Sua casa ainda esta como o senhor deixou e a vov\u00f3 continua cuidando das plantas dela. V\u00f4, o senhor iria gostar de conhecer seus netos mais novos. Dizem que as meninas da fam\u00edlia se parecem bastante. Eu gosto disso. Lamento por o senhor n\u00e3o ter recebido o tratamento contra o c\u00e2ncer de pulm\u00e3o da forma correta, mas naquela \u00e9poca ainda \u00e9ramos pessoas pouco informadas. Hoje eu fa\u00e7o faculdade, v\u00f4. Tenho 20 anos e um irm\u00e3o que ouvir\u00e1 o que tenho a dizer sobre o senhor. Ele \u00e9 um rapazinho de 11 anos de cora\u00e7\u00e3o e intelig\u00eancia incr\u00edveis. Vov\u00f4, eu sei que o senhor n\u00e3o sabia nem ler nem escrever, porque desde cedo trabalhou na agricultura e n\u00e3o haviam muitas escolas, mas de alguma forma, eu sinto que esta carta chegar\u00e1 ao senhor. E espero que fique satisfeito. Prometo cuidar bem de mam\u00e3e. Papai tamb\u00e9m faz isso muito bem e eu quero que o senhor saiba que sentimos saudades.<br \/>\nAbra\u00e7o, vov\u00f4<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Quando o senhor se foi, eu tinha 7 anos. N\u00f3s n\u00e3o est\u00e1vamos na mesma cidade. Eu lembro do telefone tocando, da minha madrinha atendendo, olhando-me e anunciando: &#8220;o vov\u00f4 morreu&#8221;. Eu n\u00e3o posso dizer o que senti naquela \u00e9poca porque eu n\u00e3o tenho certeza se podia compreender o que aquelas tr\u00eas palavras queriam dizer. Mas, [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[2],"tags":[],"class_list":["post-517","post","type-post","status-publish","format-standard","hentry","category-love-letters"],"acf":[],"_links":{"self":[{"href":"https:\/\/loveletters.avadellaira.com\/love-letters\/wp-json\/wp\/v2\/posts\/517","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/loveletters.avadellaira.com\/love-letters\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/loveletters.avadellaira.com\/love-letters\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/loveletters.avadellaira.com\/love-letters\/wp-json\/wp\/v2\/comments?post=517"}],"version-history":[{"count":0,"href":"https:\/\/loveletters.avadellaira.com\/love-letters\/wp-json\/wp\/v2\/posts\/517\/revisions"}],"wp:attachment":[{"href":"https:\/\/loveletters.avadellaira.com\/love-letters\/wp-json\/wp\/v2\/media?parent=517"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/loveletters.avadellaira.com\/love-letters\/wp-json\/wp\/v2\/categories?post=517"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/loveletters.avadellaira.com\/love-letters\/wp-json\/wp\/v2\/tags?post=517"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}